{"id":851,"count":2,"description":"","link":"https:\/\/www.morganintl.com\/en\/tag\/compensation","name":"compensation","slug":"compensation","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>compensation - Morgan International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.morganintl.com\/en\/tag\/compensation\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"compensation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.morganintl.com\/en\/tag\/compensation\" \/>\n<meta property=\"og:site_name\" content=\"Morgan International\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@morganintl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/tag\\\/compensation\",\"url\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/tag\\\/compensation\",\"name\":\"compensation - Morgan International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/tag\\\/compensation#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/tag\\\/compensation#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.morganintl.com\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"compensation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/\",\"name\":\"www.morganintl.com\",\"description\":\"Professional Certification Training\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/#organization\",\"name\":\"Morgan International\",\"url\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.morganintl.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/morgan-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.morganintl.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/morgan-logo.jpg\",\"width\":1220,\"height\":295,\"caption\":\"Morgan International\"},\"image\":{\"@id\":\"https:\\\/\\\/www.morganintl.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MorganIntl\\\/\",\"https:\\\/\\\/x.com\\\/morganintl\",\"https:\\\/\\\/www.instagram.com\\\/morganintl\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/morgan-international\\\/\",\"https:\\\/\\\/www.youtube.com\\\/morganintl8\",\"https:\\\/\\\/www.tiktok.com\\\/@morgan.intl\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"compensation - Morgan International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.morganintl.com\/en\/tag\/compensation","og_locale":"en_US","og_type":"article","og_title":"compensation","og_url":"https:\/\/www.morganintl.com\/en\/tag\/compensation","og_site_name":"Morgan International","twitter_card":"summary_large_image","twitter_site":"@morganintl","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.morganintl.com\/en\/tag\/compensation","url":"https:\/\/www.morganintl.com\/en\/tag\/compensation","name":"compensation - Morgan International","isPartOf":{"@id":"https:\/\/www.morganintl.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.morganintl.com\/en\/tag\/compensation#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.morganintl.com\/en\/tag\/compensation#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.morganintl.com\/en"},{"@type":"ListItem","position":2,"name":"compensation"}]},{"@type":"WebSite","@id":"https:\/\/www.morganintl.com\/en\/#website","url":"https:\/\/www.morganintl.com\/en\/","name":"www.morganintl.com","description":"Professional Certification Training","publisher":{"@id":"https:\/\/www.morganintl.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.morganintl.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.morganintl.com\/en\/#organization","name":"Morgan International","url":"https:\/\/www.morganintl.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.morganintl.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.morganintl.com\/wp-content\/uploads\/2023\/11\/morgan-logo.jpg","contentUrl":"https:\/\/www.morganintl.com\/wp-content\/uploads\/2023\/11\/morgan-logo.jpg","width":1220,"height":295,"caption":"Morgan International"},"image":{"@id":"https:\/\/www.morganintl.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MorganIntl\/","https:\/\/x.com\/morganintl","https:\/\/www.instagram.com\/morganintl\/","https:\/\/www.linkedin.com\/company\/morgan-international\/","https:\/\/www.youtube.com\/morganintl8","https:\/\/www.tiktok.com\/@morgan.intl"]}]}},"_links":{"self":[{"href":"https:\/\/www.morganintl.com\/en\/wp-json\/wp\/v2\/tags\/851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.morganintl.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.morganintl.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.morganintl.com\/en\/wp-json\/wp\/v2\/posts?tags=851"},{"href":"https:\/\/www.morganintl.com\/en\/wp-json\/wp\/v2\/blog?tags=851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}